{"id":344,"date":"2025-07-08T10:37:04","date_gmt":"2025-07-08T10:37:04","guid":{"rendered":"https:\/\/www.talvenmaa.com\/?page_id=344"},"modified":"2026-07-06T09:04:26","modified_gmt":"2026-07-06T09:04:26","slug":"activites-hiver","status":"publish","type":"page","link":"https:\/\/www.talvenmaa.com\/en\/nos-experiences\/activites-hiver\/","title":{"rendered":"Winter activities"},"content":{"rendered":"<style>\n\/* HERO SECTION CONTACT - m\u00eame style que l'\u00e9quipe *\/\n.hero-hiver {\n    background-image: url('https:\/\/www.talvenmaa.com\/wp-content\/uploads\/2025\/11\/PB250039-scaled.jpg');\n    background-size: cover;\n    background-position: center 70% !important;\n    background-attachment: fixed;\n    padding: 40px 20px;\n    position: relative;\n    margin-top: 30px;\n    \n    width: 100vw !important;\n    max-width: 100vw !important;\n    position: relative !important;\n    left: 50% !important;\n    right: 50% !important;\n    margin-left: -50vw !important;\n    margin-right: -50vw !important;\n    box-sizing: border-box !important;\n}\n\n\/* Reprise exacte du style de la page \u00e9quipe *\/\n.hero-hiver .intro-title {\n    font-family: 'Montserrat', sans-serif;\n    font-weight: 500 !important;\n    font-size: 40px !important;\n    color: #ffffff !important;\n    text-align: center;\n    margin-bottom: 30px;\n    line-height: 1.3;\n}\n\n.hero-hiver .intro-overlay p {\n    background-color: rgba(16, 38, 64, 0.8);\n    padding: 15px;\n    max-width: 800px;\n    margin: 0 auto;\n    color: #ffffff !important;\n    font-size: 16px;\n    font-weight : 350;\n    line-height: 1.6;\n    border-radius: 8px;\n    text-align: justify;\n    white-space: pre-line;\n}\n\n@media screen and (max-width: 768px) {\n  .hero-hiver {\n    padding: 30px 10px;\n  }\n\n  .hero-hiver .intro-title {\n    font-size: 26px;\n    margin-top: 20px;\n    padding: 0 10px;\n  }\n\n  .hero-hiver .intro-overlay {\n    padding-top: 10px;\n    background-color: rgba(16, 38, 64, 0.7);\n\n  }\n\n  .hero-hiver .intro-overlay p {\n    background-color: transparent;\n  }\n}\n\n<\/style>\n<section class=\"hero-hiver\">\n  <div class=\"intro-overlay\">\n    <h1 class=\"intro-title\">Nos exp\u00e9riences hiver<\/h1>\n    <p>Sapins emmitoufl\u00e9s, lacs gel\u00e9s ou encore aurores bor\u00e9ales majestueuses, la magie de l&rsquo;hiver finlandais n&rsquo;a d&rsquo;\u00e9gal que sa puret\u00e9. Nous vous offrons la possibilit\u00e9 d&rsquo;explorer ce th\u00e9\u00e2tre des r\u00eaves \u00e0 travers des exp\u00e9riences pens\u00e9es pour chacun. Nous privil\u00e9gions des activit\u00e9s en petits groupes ET priv\u00e9s afin de conserver l&rsquo;approche authentique qui nous caract\u00e9rise.\n<br> <strong> ATTENTION <\/strong>: Nous ne fournissons pas de v\u00eatements grand froid, bottes, ou gants. Veillez bien \u00e0 venir avec une tenue adapt\u00e9e \u00e0 la m\u00e9t\u00e9o pr\u00e9vue. En cas de doutes ou questions, n\u2019h\u00e9sitez pas \u00e0 nous contacter. <\/p> \n  <\/div>\n<\/section>\n\n<style>\n.page-subtitle {\n  font-family: 'Lato', sans-serif;\n  font-weight: 600;\n  font-size: 32px !important;\n  text-align: center;\n  color: #ffffff;\n  margin: 40px auto 20px auto;\n  max-width: 800px;\n  line-height: 1.4;\n}\n\n.slider-wrapper {\n  background-color: #eee7d9;\n  padding: 30px;\n  text-align: center;\n  border-radius: 8px;\n  margin: 40px auto;\n  width: 100%;\n  max-width: 1100px;\n  box-shadow: 0 5px 15px rgba(0,0,0,0.2);\n}\n\n.activity-subtitle {\n  font-family: 'Montserrat', sans-serif;\n  font-size: 22px !important;\n  color: #F25C05;\n  text-align: center;\n  margin-bottom: 20px;\n}\n\n.activities-grid {\n  display: grid;\n  grid-template-columns: repeat(auto-fit, minmax(320px, 1fr));\n  gap: 40px;\n  padding: 20px;\n  max-width: 1100px;\n  margin: 0 auto;\n  box-sizing: border-box;\n}\n.slider-container {\n  position: relative;\n  overflow: hidden;\n  border-radius: 8px;\n  width: 100%;\n  aspect-ratio: 3 \/ 2;\n}\n\n.slide {\n  display: none;\n  width: 100%;\n  height: 100%;\n  background-size: cover;\n  background-position: center center;\n  position: absolute;\n  top: 0;\n  left: 0;\n}\n\n.slide.active {\n  display: block;\n}\n\n.activity-description {\n  background: rgba(16, 38, 64, 0.8) !important;\n  color: #ffffff;\n  padding: 20px;\n  font-size: 16px;\n  font-family: 'Lato', sans-serif;\n  border-radius: 0 0 8px 8px;\n  text-align: justify;\n}\n\n.activity-description p {\n  margin: 4px 0;\n  color: #ffffff;\n}\n\n.activity-description strong {\n  color: #ffffff;\n}\n.price-box {\n  position: absolute;\n  top: 10px;\n  right: 10px;\n  background: rgba(245, 236, 220, 0.9);\n  color: #102640;\n  padding: 8px 12px;\n  border-radius: 4px;\n  font-weight: bold;\n  font-size: 16px;\n  font-family: 'Lato', sans-serif;\n}\n\n\n.slider-arrow {\n  position: absolute;\n  top: 50%;\n  transform: translateY(-50%);\n  font-size: 30px;\n  color: #ffffff;\n  background-color: rgba(0, 0, 0, 0.5);\n  padding: 8px 12px;\n  border-radius: 50%;\n  cursor: pointer;\n  z-index: 10;\n  transition: background 0.3s;\n  user-select: none;\n}\n\n.slider-arrow:hover {\n  background-color: rgba(0, 0, 0, 0.6);\n}\n\n.slider-arrow.left {\n  left: 10px;\n}\n\n.slider-arrow.right {\n  right: 10px;\n}\n\n.reserve-btn {\n  display: inline-block;\n  background-color: #F25C05;\n  color: #ffffff !important;\n  padding: 12px 20px;\n  margin-top: 20px;\n  text-decoration: none;\n  font-weight: bold;\n  border-radius: 6px;\n  transition: background 0.3s;\n  font-family: 'Montserrat', sans-serif;\n  font-size: 15px;\n  display: block;\n  width: fit-content;\n  margin-left: auto;\n  margin-right: auto;\n}\n\n.reserve-btn:hover {\n  background-color: #d44a04;\n}\n\n.info-paragraph {\n  background-color: #F5ECDC;\n  outline: 2px dashed #102640;\n  outline-offset: -10px;\n  color: #ffffff;\n  font-family: 'Lato', sans-serif;\n  font-size: 16px !important;\n  padding: 20px;\n  border-radius: 8px;\n  width: 90%;\n  max-width: 700px;\n  margin: 40px auto 20px auto;\n  text-align: justify;\n  box-shadow: 0 5px 15px rgba(0,0,0,0.15);\n}\n\n.info-paragraph p {\n  margin: 10px 0;\n  color: #102640;\n}\n\n@media screen and (max-width: 768px) {\n  .hero-banner {\n    height: 250px;\n  }\n\n  .activity-subtitle {\n    font-size: 24px;\n  }\n\n  .slide-description {\n    font-size: 14px;\n    padding: 10px 15px;\n  }\n\n  .slider-wrapper {\n    padding: 20px;\n  }\n\n  .reserve-btn {\n    font-size: 14px;\n    padding: 10px 16px;\n  }\n}\n\n.desktop-only {\n  display: block;\n}\n\n.mobile-only {\n  display: none;\n}\n\n@media screen and (max-width: 768px) {\n  .desktop-only {\n    display: none;\n  }\n\n  .mobile-only {\n    display: block;\n    background: rgba(16, 38, 64, 1);\n    border-radius: 0 0 8px 8px;\n    padding: 12px 16px;\n    color: white;\n    font-size: 14px;\n    line-height: 1.5;\n    text-align: justify;\n    font-family: 'Lato', sans-serif;\n    margin-top: -5px;\n  }\n}\n<\/style>\n\n\n<\/style>\n\n<section class=\"activites-section\">\n<div class=\"activities-grid\">\n\n <!-- ACTIVIT\u00c9 1 : Balade en raquettes avec nos chiens nordiques -->\n  <div class=\"slider-wrapper\">\n    <h2 class=\"activity-subtitle\">Balade en raquettes avec nos chiens nordiques<\/h2>\n\n    <div class=\"slider-container\" id=\"slider1\">\n      <div class=\"slide active\" style=\"background-image: url('https:\/\/www.talvenmaa.com\/wp-content\/uploads\/2026\/02\/IMG-20260220-WA0067.jpg');\" aria-label=\"Randonn\u00e9e en raquettes avec chiens nordiques Talvenmaa\">\n      <\/div>\n      <div class=\"slide\" style=\"background-image: url('https:\/\/www.talvenmaa.com\/wp-content\/uploads\/2026\/02\/IMG_20260201_141218-scaled-e1771667513548.jpg');\" aria-label=\"Chien nordique Samoy\u00e8de en randonn\u00e9e Talvenmaa\">\n      <\/div>\n <div class=\"slide\" style=\"background-image: url('https:\/\/www.talvenmaa.com\/wp-content\/uploads\/2025\/12\/PC2605663-scaled.jpg');\" aria-label=\"Chien nordique Samoy\u00e8de en randonn\u00e9e Talvenmaa\">\n      <\/div>\n      <div class=\"slider-arrow left\" onclick=\"prevSlide('slider1')\">&#10094;<\/div>\n      <div class=\"slider-arrow right\" onclick=\"nextSlide('slider1')\">&#10095;<\/div>\n    <\/div>\n    <div class=\"activity-description\">\n      <p>Rencontrez notre meute de samoy\u00e8des et laikas, v\u00e9ritables chiens nordiques adapt\u00e9s au grand nord. Nos chiens sont des membres de notre famille, ils sont habitu\u00e9s au contact humain, ils vivent avec nous \u00e0 la maison et nous accompagnent dans toutes sortes d&rsquo;activit\u00e9s. Equip\u00e9s d&rsquo;un baudrier et d&rsquo;une longe \u00e9lastique, vous partirez \u00e0 la d\u00e9couverte de la nature lapone tract\u00e9 par l&rsquo;un de nos chiens. Votre guide vous partagera son savoir sur la nature finlandaise tout au long du parcours et lors de la pause au coin du feu.<\/p>\n\n        <br><p><strong>Pour qui ?<\/strong> Pour celles et ceux qui souhaitent d\u00e9couvrir la Laponie enneig\u00e9e lors d\u2019une sortie active, en petit groupe, aux c\u00f4t\u00e9s de nos chiens et accompagn\u00e9s par un guide passionn\u00e9 de nature finlandaise. (Attention, il ne s&rsquo;agit pas d&rsquo;une sortie en traineau).<\/p>\n        <br> <p><strong>Nombre max :<\/strong> 6 personnes<\/p>\n        <p><strong>Lieu de d\u00e9part :<\/strong><br> Talvenmaa, Maaninkavaarantie 295, Posio <\/p>  \n\n        <br><p><strong> Attention : <\/strong> Nos chiens sont entra\u00een\u00e9s pour la traction, un minimum de condition physique est n\u00e9cessaire. Les chiens seront attribu\u00e9s selon leur puissance, les enfants partageront un chien avec un adulte.<\/p>\n    <\/div>\n\n    <a href=\"https:\/\/fareharbor.com\/embeds\/book\/talvenmaa\/items\/662769\/?full-items=yes&#038;flow=1467736\" class=\"reserve-btn\">Tarifs et calendrier<\/a>\n  <\/div>\n\n  <!-- ACTIVIT\u00c9 2 : Initiation tra\u00eeneau \u00e0 chiens -->\n  <div class=\"slider-wrapper\">\n    <h2 id=\"traineau\" class=\"activity-subtitle\">Initiation tra\u00eeneau \u00e0 chiens (max 2 adultes \/ 150kg)<\/h2>\n    <div class=\"slider-container\" id=\"slider3\">\n      <div class=\"slide active\" style=\"background-image: url('https:\/\/www.talvenmaa.com\/wp-content\/uploads\/2026\/02\/IMG_20260211_134600-scaled.jpg');\" aria-label=\"Conduite de tra\u00eeneau \u00e0 chiens Talvenmaa\">\n      <\/div>\n      <div class=\"slide\" style=\"background-image: url('https:\/\/www.talvenmaa.com\/wp-content\/uploads\/2026\/02\/P2021055-scaled.jpg');\" aria-label=\"Attelage nordique pour deux personnes\">\n      <\/div>\n <div class=\"slide\" style=\"background-image: url('https:\/\/www.talvenmaa.com\/wp-content\/uploads\/2026\/01\/IMG_20251216_1413042-scaled.jpg');\" aria-label=\"Attelage nordique pour deux personnes\">\n      <\/div>\n\n      <div class=\"slider-arrow left\" onclick=\"prevSlide('slider3')\">&#10094;<\/div>\n      <div class=\"slider-arrow right\" onclick=\"nextSlide('slider3')\">&#10095;<\/div>\n    <\/div>\n    <div class=\"activity-description\">\n      <p> Nos chiens sont des membres \u00e0 part enti\u00e8re de notre famille. Afin de leur laisser le choix de vivre tous ensemble, avec nous \u00e0 la maison, nous avons d\u00e9cid\u00e9 de n&rsquo;avoir qu&rsquo;un seul attelage. Cette activit\u00e9 est donc r\u00e9serv\u00e9e aux couples, duos, voyageurs solo ou parent solo avec 1 ou 2 jeunes enfants. L&rsquo;activit\u00e9 est priv\u00e9e, un seul traineau par sortie. Nos chiens sont entrain\u00e9s d\u00e8s l&rsquo;automne en kart \u00e0 roues, ils ne font qu&rsquo;un tour par jour, et alternent avec des cani-rando et des jours de repos afin de les garder motiv\u00e9s et en bonne condition mentale et physique.<\/p><br> \n\n<br><p><strong>Pour qui ?<\/strong> Les amoureux de nature et d&rsquo;animaux qui veulent vivre une exp\u00e9rience priv\u00e9e et imnmersive, rare en Laponie. Celles et ceux, pour qui le bien \u00eatre animal est une priorit\u00e9 et qui ne souhaitent pas participer au tourisme de masse et \u00e0 l&rsquo;exploitation animale.<\/p><br>\n\n        <p><strong> Nombre max :<\/strong> 2 personnes<\/p>\n        <p><strong>Lieu de d\u00e9part :<\/strong><br> Talvenmaa, Maaninkavaarantie 295, Posio <\/p>\n        <br><p>Afin de pr\u00e9server la sant\u00e9 de nos chiens,<strong> le poids total maximum des participants ne doit pas exc\u00e9der 150 kg.<\/strong><\/p><br>\n    <\/div>\n    <a href=\"https:\/\/fareharbor.com\/embeds\/book\/talvenmaa\/items\/662815\/?full-items=yes&#038;flow=1467736\" class=\"reserve-btn\">Tarifs et calendrier<\/a>\n  <\/div>\n\n\n  <!-- ACTIVIT\u00c9 3 : Safari en motoneige -->\n  <div class=\"slider-wrapper\">\n    <h2 class=\"activity-subtitle\">Safari priv\u00e9 guid\u00e9 en motoneige<\/h2>\n    \n    <div class=\"slider-container\" id=\"slider2\">\n      <div class=\"slide active\" style=\"background-image: url('https:\/\/www.talvenmaa.com\/wp-content\/uploads\/2026\/01\/P1180800-scaled.jpg');\" aria-label=\"Initiation \u00e0 la motoneige en Laponie\">\n      <\/div>\n      <div class=\"slide\" style=\"background-image: url('https:\/\/www.talvenmaa.com\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-15-at-16.36.56.jpeg');\" aria-label=\"Motoneige Talvenmaa\">\n      <\/div>\n <div class=\"slide\" style=\"background-image: url('https:\/\/www.talvenmaa.com\/wp-content\/uploads\/2026\/01\/P1180801-scaled.jpg');\" aria-label=\"Safari laponie motoneige\">\n      <\/div>\n      <div class=\"slider-arrow left\" onclick=\"prevSlide('slider2')\">&#10094;<\/div>\n      <div class=\"slider-arrow right\" onclick=\"nextSlide('slider2')\">&#10095;<\/div>\n    <\/div>\n    <div class=\"activity-description\">\n    <p>Axel, votre guide, vous initie \u00e0 la conduite de la motoneige et vous emm\u00e8ne d\u00e9couvrir des paysages immacul\u00e9s \u00e0 travers lac et for\u00eats. Comme pour toutes nos activit\u00e9s, vous serez seuls avec votre guide priv\u00e9 permettant de vous adapter \u00e0 votre rythme et de faire des pauses si besoin.<\/p>\n     \n      <br><p><strong>Pour qui ?<\/strong> Aventuriers \u00e0 la recherche de sensations fortes, explorateurs souhaitant d\u00e9couvrir la nature d&rsquo;une autre mani\u00e8re, sur des pistes hors des sentiers battus.<\/p><br>\n\n      <p><strong>Nombre max :<\/strong> 4 adultes + 2 enfants <\/p>\n      <p><strong>Lieu de d\u00e9part :<\/strong><br> Talvenmaa, Maaninkavaarantie 295, Posio <\/p>\n    <\/div>\n    <a href=\"https:\/\/fareharbor.com\/embeds\/book\/talvenmaa\/?full-items=yes&#038;flow=1590525\" class=\"reserve-btn\">Tarifs et calendrier<\/a>\n  <\/div>\n\n \n  <!-- ACTIVIT\u00c9 4 : Exploration en ski-raquettes (ski alta\u00ef) -->\n  <div class=\"slider-wrapper\">\n    <h2 id=\"traineau\" class=\"activity-subtitle\">Exploration en ski-raquettes<\/h2>\n    <div class=\"slider-container\" id=\"slider5\">\n      <div class=\"slide active\" style=\"background-image: url('https:\/\/www.talvenmaa.com\/wp-content\/uploads\/2026\/02\/P2131219-scaled.jpg');\" aria-label=\"K=SKi raquettes Talvenmaa\">\n      <\/div>\n <div class=\"slide\" style=\"background-image: url('https:\/\/www.talvenmaa.com\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-15-at-16.36.59.jpeg');\" aria-label=\"ski raquettes\">\n      <\/div>\n      <div class=\"slide\" style=\"background-image: url('https:\/\/www.talvenmaa.com\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-15-at-16.36.58.jpeg');\" aria-label=\"ski alta\u00ef\">\n      <\/div>\n      <div class=\"slider-arrow left\" onclick=\"prevSlide('slider5')\">&#10094;<\/div>\n      <div class=\"slider-arrow right\" onclick=\"nextSlide('slider5')\">&#10095;<\/div>\n    <\/div>\n    <div class=\"activity-description\">\n      <p> Partez \u00e0 la d\u00e9couverte du ski Alta\u00ef, une exp\u00e9rience unique qui combine glisse et aventure en pleine nature. Que vous soyez d\u00e9butant ou skieur confirm\u00e9, le ski alta\u00ef est une parfaite altervative entre les sensations procur\u00e9es par les raquettes et la glisse du ski, sans la difficult\u00e9 du ski de fond. Ils permettent d&rsquo;explorer la nature en neige profonde. Cette activit\u00e9 vous offre une immersion totale dans un environnement pr\u00e9serv\u00e9, pour un moment inoubliable avec votre guide priv\u00e9. <\/p> \n\n<br><p><strong>Pour qui ?<\/strong> Pour celles et ceux qui souhaitent d\u00e9couvrir une activit\u00e9 sportive originale, peu propos\u00e9e en Laponie et accessible \u00e0 tous niveaux.<\/p>\n\n        <br><p><strong>Nombre max :<\/strong> 4 personnes <\/p>\n        <p><strong>Lieu de d\u00e9part :<\/strong><br> Talvenmaa, Maaninkavaarantie 295, Posio <\/p>\n    <\/div>\n    <a href=\"https:\/\/fareharbor.com\/embeds\/book\/talvenmaa\/items\/663061\/?full-items=yes&#038;flow=1465970\" class=\"reserve-btn\">Tarifs et calendrier<\/a>\n  <\/div>\n\n <!-- ACTIVIT\u00c9 5 : Randonn\u00e9e guid\u00e9e \u00e0 Riisitunturi -->\n  <div class=\"slider-wrapper\">\n    <h2 id=\"raquettes\" class=\"activity-subtitle\">Randonn\u00e9e guid\u00e9e \u00e0 Riisitunturi<\/h2>\n    <div class=\"slider-container\" id=\"slider4\">\n      <div class=\"slide active\" style=\"background-image: url('https:\/\/www.talvenmaa.com\/wp-content\/uploads\/2026\/02\/P2010993-scaled.jpg');\" aria-label=\"Randonn\u00e9e en raquettes Talvenmaa\">\n      <\/div>\n      <div class=\"slide\" style=\"background-image: url('https:\/\/www.talvenmaa.com\/wp-content\/uploads\/2026\/02\/IMG_20260201_1409372-scaled.jpg');\" aria-label=\"Randonn\u00e9e en raquettes\">\n      <\/div>\n      <div class=\"slider-arrow left\" onclick=\"prevSlide('slider4')\">&#10094;<\/div>\n      <div class=\"slider-arrow right\" onclick=\"nextSlide('slider4')\">&#10095;<\/div>\n    <\/div>\n    <div class=\"activity-description\">\n      <p> D\u00e9couvrez l&rsquo;un des plus beaux parcs nationaux de Finlande emmitoufl\u00e9 dans son beau manteau d&rsquo;hiver ; Riisitunturi est certes r\u00e9put\u00e9 pour ses sapins pi\u00e9g\u00e9s dans la poudreuse, mais ce parc offre \u00e9galement des panoramas \u00e0 couper le souffle. Axel, votre guide, apportera une touche p\u00e9dagogique \u00e0 cette visite et vous parlera de la faune et de la flore en Laponie. Comme pour toutes nos activit\u00e9s, vous serez seuls avec votre guide priv\u00e9. La randonn\u00e9e se fait \u00e0 pied ou en raquettes si n\u00e9cessaire.<\/p> <br>\n\n<br><p><strong>Pour qui ?<\/strong> Les voyageurs souhaitant profiter des connaissances d&rsquo;un guide locale sur la nature et la vie en Laponie et \u00eatre accompagn\u00e9s durant cette magnifique espacade. En cas de fortes chutes de neige et de vent, la piste peut \u00eatre recouverte et votre guide vous ouvrira la voie.<\/p><br>\n\n        <p><strong> Nombre max :<\/strong> 6 personnes<\/p>\n        <p><strong>Lieu de d\u00e9part :<\/strong> Parking du parc national de Riisitunturi, Posio <\/p>\n    <\/div>\n    <a href=\"https:\/\/fareharbor.com\/embeds\/book\/talvenmaa\/items\/662840\/?full-items=yes&#038;flow=1465970\" class=\"reserve-btn\">Tarifs et calendrier<\/a>\n  <\/div>\n\n\n\n<!-- ACTIVIT\u00c9 6 : Activit\u00e9s nocturnes -->\n  <div class=\"slider-wrapper\">\n    <h2 id=\"traineau\" class=\"activity-subtitle\">Activit\u00e9s nocturnes<\/h2>\n    <div class=\"slider-container\" id=\"slider7\">\n      <div class=\"slide active\" style=\"background-image: url('https:\/\/www.talvenmaa.com\/wp-content\/uploads\/2025\/07\/aurores-laponie-talvenmaa-scaled.jpg');\" aria-label=\"northern lights\">\n      <\/div>\n      <div class=\"slide\" style=\"background-image: url('https:\/\/www.talvenmaa.com\/wp-content\/uploads\/2025\/12\/PC200328-scaled.jpg');\" aria-label=\"northern lights\">\n      <\/div>\n      <div class=\"slider-arrow left\" onclick=\"prevSlide('slider7')\">&#10094;<\/div>\n      <div class=\"slider-arrow right\" onclick=\"nextSlide('slider7')\">&#10095;<\/div>\n    <\/div>\n    <div class=\"activity-description\">\n      <p> D\u00e9couvrez la magie hivernale de la Laponie Finlandaise lors de la nuit polaire. Nous proposons deux formules pour une aventure nocturne en raquettes : sortie courte avec pause sur le lac au coin du feu ou soir\u00e9e traditionnelle avec saumon grill\u00e9 dans la lapin kota.<br>\nAttention, il ne s&rsquo;agit pas d&rsquo;une chasse aux aurores bor\u00e9ales, mais d&rsquo;une exp\u00e9rience nocturne avec guide priv\u00e9. Une grande partie de la balade se d\u00e9roulant sur le lac, nous serons parfaitement positionn\u00e9s pour observer les aurores bor\u00e9ales, si celles-ci veulent bien se montrer. Cela d\u00e9pend \u00e9videmment des conditions m\u00e9t\u00e9o et de l&rsquo;activit\u00e9 solaire.<\/p>\n<p> Nous proposons aussi une sortie motoneige en nocturne, destin\u00e9e de pr\u00e9f\u00e9rence aux clients ayant d\u00e9j\u00e0 conduit ce type de v\u00e9hicule.\n<\/p><br>\n\n        <p><strong> Nombre max :<\/strong> 6 personnes <\/p>\n       <p><strong>Lieu de l&rsquo;activit\u00e9 :<\/strong><br> Talvenmaa, Maaninkavaarantie 295, Posio\n    <\/div><\/p>\n    <a href=\"https:\/\/fareharbor.com\/embeds\/book\/talvenmaa\/?full-items=yes&#038;flow=1590520\"class=\"reserve-btn\">Tarifs et calendrier<\/a>\n  <\/div>\n\n\n<!-- ACTIVIT\u00c9 8 : Visite de la ferme de rennes-->\n  <div class=\"slider-wrapper\">\n    <h2 id=\"rennes\" class=\"activity-subtitle\">Ferme des rennes &#8211; Traduction en fran\u00e7ais<\/h2>\n    <div class=\"slider-container\" id=\"slider9\">\n      <div class=\"slide active\" style=\"background-image: url('https:\/\/www.talvenmaa.com\/wp-content\/uploads\/2026\/02\/IMG_20251230_144706-scaled.jpg');\" aria-label=\"reindeer lapland\">\n      <\/div>\n      <div class=\"slide\" style=\"background-image: url('https:\/\/www.talvenmaa.com\/wp-content\/uploads\/2025\/12\/IMG_20251205_155223-scaled-e1766674590751.jpg');\" aria-label=\"reindeer lapland\"> \n      <\/div>\n<div class=\"slide\" style=\"background-image: url('https:\/\/www.talvenmaa.com\/wp-content\/uploads\/2026\/01\/IMG-20251231-WA0047.jpg');\" aria-label=\"reindeer lapland\"> \n      <\/div>\n\n      <div class=\"slider-arrow left\" onclick=\"prevSlide('slider9')\">&#10094;<\/div>\n      <div class=\"slider-arrow right\" onclick=\"nextSlide('slider9')\">&#10095;<\/div>\n    <\/div>\n    <div class=\"activity-description\">\n      <p>Le bien \u00eatre animal \u00e9tant notre priorit\u00e9, nous avons choisi notre partenaire avec soin. Chez Manne et Christina, vous d\u00e9couvrirez l&rsquo;univers d&rsquo;une ferme de rennes ou les animaux sont bien trait\u00e9s et consid\u00e9r\u00e9s. Pas de tours \u00e0 la chaine, pas de grands groupes, vous profiterez d&rsquo;une activit\u00e9 intimiste en petit groupe. Activit\u00e9 r\u00e9alis\u00e9e par notre partenaire Ylitalon Poromatkailu. Prestation de traduction en francais dispens\u00e9e par Talvenmaa.<\/p><br>\n     \n        <p><strong> Nombre max. de participants :<\/strong> 8 personnes (activit\u00e9 non priv\u00e9e)<\/p>\n    <\/div>\n    <a href=\"https:\/\/www.talvenmaa.com\/contact\/\" class=\"reserve-btn\">Nous contacter<\/a>\n  <\/div>\n\n\n<!-- ACTIVIT\u00c9 9 : Activit\u00e9s combin\u00e9es et \u00e9v\u00e8nements-->\n  <div class=\"slider-wrapper\">\n    <h2 id=\"traineau\" class=\"activity-subtitle\">Activit\u00e9s combin\u00e9es et \u00e9v\u00e8nements<\/h2>\n    <div class=\"slider-container\" id=\"slider8\">\n      <div class=\"slide active\" style=\"background-image: url('https:\/\/www.talvenmaa.com\/wp-content\/uploads\/2025\/11\/PB250039-scaled.jpg');\" aria-label=\"ice fishing lapland\">\n      <\/div>\n      <div class=\"slide\" style=\"background-image: url('https:\/\/www.talvenmaa.com\/wp-content\/uploads\/2025\/09\/PC317907-scaled-e1757231794716.jpg');\" aria-label=\"ice fishing lapland\">\n        <\/div>\n      <div class=\"slide\" style=\"background-image: url('https:\/\/www.talvenmaa.com\/wp-content\/uploads\/2025\/09\/PC317907-scaled-e1757231794716.jpg');\" aria-label=\"ice fishing lapland\">\n       \n      <\/div>\n      <div class=\"slider-arrow left\" onclick=\"prevSlide('slider8')\">&#10094;<\/div>\n      <div class=\"slider-arrow right\" onclick=\"nextSlide('slider8')\">&#10095;<\/div>\n    <\/div>\n    <div class=\"activity-description\">\n      <p>Vous souhaitez profiter d&rsquo;une journ\u00e9e compl\u00e8te d&rsquo;activit\u00e9s ? Consultez notre offre compl\u00e8te et nos journ\u00e9es combin\u00e9es en duo ou en famille. Vous souhaitez cr\u00e9er une journ\u00e9e sur-mesure ou pour un \u00e9v\u00e8nement particulier ? Nh\u00e9sitez pas \u00e0 nous contacter. Etant une entreprise familiale, nous sommes flexibles sur nos offres et pouvons vous proposer une exp\u00e9rience sur-mesure. <br>\n\n    <\/div>\n    <a href=\"https:\/\/fareharbor.com\/embeds\/book\/talvenmaa\/?full-items=yes&#038;flow=1577511\" class=\"reserve-btn\">Consulter toutes nos offres<\/a>\n  <\/div>\n\n<!-- ACTIVIT\u00c9 10 : Miki -->\n  <div class=\"slider-wrapper\">\n    <h2 id=\"traineau\" class=\"activity-subtitle\">Atelier de c\u00e9ramique Miki Studio<\/h2>\n    <div class=\"slider-container\" id=\"slider10\">\n      <div class=\"slide active\" style=\"background-image: url('https:\/\/www.talvenmaa.com\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-27-at-15.57.16.jpeg');\" aria-label=\"miki studio lapland\">\n      <\/div>\n      <div class=\"slide\" style=\"background-image: url('https:\/\/www.talvenmaa.com\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-27-at-15.54.54.jpeg');\" aria-label=\"ceramique lapland\">\n        <\/div>\n      <div class=\"slide\" style=\"background-image: url('https:\/\/www.talvenmaa.com\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-27-at-15.55.31.jpeg');\" aria-label=\"miki studio lapland\">\n       \n      <\/div>\n      <div class=\"slider-arrow left\" onclick=\"prevSlide('slider10')\">&#10094;<\/div>\n      <div class=\"slider-arrow right\" onclick=\"nextSlide('slider10')\">&#10095;<\/div>\n    <\/div>\n    <div class=\"activity-description\">\n      <p>Envie de repartir avec un souvenir unique, v\u00e9ritable symbole de votre voyage dans le Grand Nord ? Posio, berceau de la c\u00e9ramique et terre d\u2019inspiration pour de nombreux artistes, vous ouvre ses portes. Miki, artiste d\u2019origine cor\u00e9enne, vous invite dans son atelier pour partager son savoir-faire et vous guider dans la cr\u00e9ation de votre propre chouette harfang en c\u00e9ramique.\nAtelier anim\u00e9 par Miki Studio, \u00e0 Posio.<br>\n\n    <\/div>\n    <a href=\"https:\/\/mikistudio.fi\/i\/workshop\" class=\"reserve-btn\">Contacter Miki<\/a>\n  <\/div>\n\n <\/div>\n\n\n\n<div class=\"info-paragraph\">\n<p><strong>&#x2139;&#xfe0f; Informations importantes<\/strong><\/p>\n<p><strong>Equipements : <\/strong> Le mat\u00e9riel de s\u00e9curit\u00e9 vous est fourni : crampons, raquettes, baudriers, casques&#8230; \nNous ne fournissons en revanche pas de v\u00eatements grand froid, bottes, ou gants. Veillez bien \u00e0 venir avec une tenue adapt\u00e9e \u00e0 la m\u00e9t\u00e9o pr\u00e9vue. En cas de doutes ou questions, n&rsquo;h\u00e9sitez surtout pas \u00e0 nous contacter. <\/p>\n  <p><strong>Activit\u00e9s motoneige :<\/strong> Vous partagerez le v\u00e9hicule avec la personne de votre choix, un changement de conducteur est pr\u00e9vu \u00e0 mi-chemin si souhait\u00e9. En cas de nombre impair ou de demande sp\u00e9cifique pour \u00eatre seul sur le v\u00e9hicule, un suppl\u00e9ment sera appliqu\u00e9. Un permis B valide devra \u00eatre pr\u00e9sent\u00e9 pour chaque conducteur. Les enfants <strong>de moins de 1m40<\/strong>, n&rsquo;atteignant pas les cale-pieds, devront s&rsquo;asseoir dans un tra\u00eeneau, tract\u00e9 par le guide. Il est \u00e9videmment interdit de conduire sous l&rsquo;influence de l&rsquo;alcool, des contr\u00f4les ont parfois lieu sur les itin\u00e9raires. Une franchise est appliqu\u00e9e en cas d&rsquo;incident avec un v\u00e9hicule (voir section \u00ab\u00a0CGV\u00a0\u00bb).<\/p>\n  <p>Un minimum de condition physique est requis pour toutes nos activit\u00e9s.<\/p>\n  <p><strong>Conditions d&rsquo;annulation :<\/strong> Les activit\u00e9s peuvent \u00eatre reprogramm\u00e9es ou annul\u00e9es en cas de conditions m\u00e9t\u00e9orologiques extr\u00eames (voir section \u00ab\u00a0CGV\u00a0\u00bb).<\/p>\n<\/div>\n<\/section>\n\n<script>\nfunction nextSlide(sliderId) {\n  const slider = document.getElementById(sliderId);\n  const slides = slider.querySelectorAll('.slide');\n  const current = Array.from(slides).findIndex(slide => slide.classList.contains('active'));\n  slides[current].classList.remove('active');\n  const nextIndex = (current + 1) % slides.length;\n  slides[nextIndex].classList.add('active');\n}\n\nfunction prevSlide(sliderId) {\n  const slider = document.getElementById(sliderId);\n  const slides = slider.querySelectorAll('.slide');\n  const current = Array.from(slides).findIndex(slide => slide.classList.contains('active'));\n  slides[current].classList.remove('active');\n  const prevIndex = (current - 1 + slides.length) % slides.length;\n  slides[prevIndex].classList.add('active');\n}\n<\/script>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nos exp\u00e9riences hiver Sapins emmitoufl\u00e9s, lacs gel\u00e9s ou encore aurores bor\u00e9ales majestueuses, la magie de l&rsquo;hiver finlandais n&rsquo;a d&rsquo;\u00e9gal que sa puret\u00e9. Nous vous offrons la possibilit\u00e9 d&rsquo;explorer ce th\u00e9\u00e2tre des r\u00eaves \u00e0 travers des exp\u00e9riences pens\u00e9es pour chacun. Nous privil\u00e9gions des activit\u00e9s en petits groupes ET priv\u00e9s afin de conserver l&rsquo;approche authentique qui nous [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1579,"parent":921,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"saved_in_kubio":true,"footnotes":""},"class_list":["post-344","page","type-page","status-publish","has-post-thumbnail","hentry"],"kubio_ai_page_context":{"short_desc":"","purpose":"general"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Guide priv\u00e9 en Laponie : motoneige, chiens de tra\u00eeneau, p\u00eache...<\/title>\n<meta name=\"description\" content=\"Safari en motoneige, raquettes, chiens de tra\u00eeneau : d\u00e9couvrez la magie de la Laponie avec votre guide priv\u00e9 francophone.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.talvenmaa.com\/en\/nos-experiences\/activites-hiver\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Guide priv\u00e9 en Laponie : motoneige, chiens de tra\u00eeneau, p\u00eache...\" \/>\n<meta property=\"og:description\" content=\"Safari en motoneige, raquettes, chiens de tra\u00eeneau : d\u00e9couvrez la magie de la Laponie avec votre guide priv\u00e9 francophone.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.talvenmaa.com\/en\/nos-experiences\/activites-hiver\/\" \/>\n<meta property=\"og:site_name\" content=\"Talvenmaa - Voyage en terre nordique\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/talvenmaa\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-06T09:04:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.talvenmaa.com\/wp-content\/uploads\/2026\/01\/P1180823-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1919\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.talvenmaa.com\\\/nos-experiences\\\/activites-hiver\\\/\",\"url\":\"https:\\\/\\\/www.talvenmaa.com\\\/nos-experiences\\\/activites-hiver\\\/\",\"name\":\"Guide priv\u00e9 en Laponie : motoneige, chiens de tra\u00eeneau, p\u00eache...\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.talvenmaa.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.talvenmaa.com\\\/nos-experiences\\\/activites-hiver\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.talvenmaa.com\\\/nos-experiences\\\/activites-hiver\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.talvenmaa.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/P1180823-scaled.jpg\",\"datePublished\":\"2025-07-08T10:37:04+00:00\",\"dateModified\":\"2026-07-06T09:04:26+00:00\",\"description\":\"Safari en motoneige, raquettes, chiens de tra\u00eeneau : d\u00e9couvrez la magie de la Laponie avec votre guide priv\u00e9 francophone.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.talvenmaa.com\\\/nos-experiences\\\/activites-hiver\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.talvenmaa.com\\\/nos-experiences\\\/activites-hiver\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.talvenmaa.com\\\/nos-experiences\\\/activites-hiver\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.talvenmaa.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/P1180823-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.talvenmaa.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/P1180823-scaled.jpg\",\"width\":2560,\"height\":1919,\"caption\":\"OLYMPUS DIGITAL CAMERA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.talvenmaa.com\\\/nos-experiences\\\/activites-hiver\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.talvenmaa.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nos exp\u00e9riences\",\"item\":\"https:\\\/\\\/www.talvenmaa.com\\\/nos-experiences\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Activit\u00e9s hiver\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.talvenmaa.com\\\/#website\",\"url\":\"https:\\\/\\\/www.talvenmaa.com\\\/\",\"name\":\"Talvenmaa - Voyage en terre nordique\",\"description\":\"S\u00e9jours multi-activit\u00e9s et exp\u00e9riences en Laponie\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.talvenmaa.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.talvenmaa.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.talvenmaa.com\\\/#organization\",\"name\":\"Talvenmaa\",\"url\":\"https:\\\/\\\/www.talvenmaa.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.talvenmaa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.talvenmaa.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Rendu-final-01-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.talvenmaa.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Rendu-final-01-1-scaled.jpg\",\"width\":2560,\"height\":2560,\"caption\":\"Talvenmaa\"},\"image\":{\"@id\":\"https:\\\/\\\/www.talvenmaa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/talvenmaa\",\"https:\\\/\\\/www.instagram.com\\\/alex.axel.experience.nordique\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Guide priv\u00e9 en Laponie : motoneige, chiens de tra\u00eeneau, p\u00eache...","description":"Safari en motoneige, raquettes, chiens de tra\u00eeneau : d\u00e9couvrez la magie de la Laponie avec votre guide priv\u00e9 francophone.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.talvenmaa.com\/en\/nos-experiences\/activites-hiver\/","og_locale":"en_GB","og_type":"article","og_title":"Guide priv\u00e9 en Laponie : motoneige, chiens de tra\u00eeneau, p\u00eache...","og_description":"Safari en motoneige, raquettes, chiens de tra\u00eeneau : d\u00e9couvrez la magie de la Laponie avec votre guide priv\u00e9 francophone.","og_url":"https:\/\/www.talvenmaa.com\/en\/nos-experiences\/activites-hiver\/","og_site_name":"Talvenmaa - Voyage en terre nordique","article_publisher":"https:\/\/www.facebook.com\/talvenmaa","article_modified_time":"2026-07-06T09:04:26+00:00","og_image":[{"width":2560,"height":1919,"url":"https:\/\/www.talvenmaa.com\/wp-content\/uploads\/2026\/01\/P1180823-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.talvenmaa.com\/nos-experiences\/activites-hiver\/","url":"https:\/\/www.talvenmaa.com\/nos-experiences\/activites-hiver\/","name":"Guide priv\u00e9 en Laponie : motoneige, chiens de tra\u00eeneau, p\u00eache...","isPartOf":{"@id":"https:\/\/www.talvenmaa.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.talvenmaa.com\/nos-experiences\/activites-hiver\/#primaryimage"},"image":{"@id":"https:\/\/www.talvenmaa.com\/nos-experiences\/activites-hiver\/#primaryimage"},"thumbnailUrl":"https:\/\/www.talvenmaa.com\/wp-content\/uploads\/2026\/01\/P1180823-scaled.jpg","datePublished":"2025-07-08T10:37:04+00:00","dateModified":"2026-07-06T09:04:26+00:00","description":"Safari en motoneige, raquettes, chiens de tra\u00eeneau : d\u00e9couvrez la magie de la Laponie avec votre guide priv\u00e9 francophone.","breadcrumb":{"@id":"https:\/\/www.talvenmaa.com\/nos-experiences\/activites-hiver\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.talvenmaa.com\/nos-experiences\/activites-hiver\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.talvenmaa.com\/nos-experiences\/activites-hiver\/#primaryimage","url":"https:\/\/www.talvenmaa.com\/wp-content\/uploads\/2026\/01\/P1180823-scaled.jpg","contentUrl":"https:\/\/www.talvenmaa.com\/wp-content\/uploads\/2026\/01\/P1180823-scaled.jpg","width":2560,"height":1919,"caption":"OLYMPUS DIGITAL CAMERA"},{"@type":"BreadcrumbList","@id":"https:\/\/www.talvenmaa.com\/nos-experiences\/activites-hiver\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.talvenmaa.com\/"},{"@type":"ListItem","position":2,"name":"Nos exp\u00e9riences","item":"https:\/\/www.talvenmaa.com\/nos-experiences\/"},{"@type":"ListItem","position":3,"name":"Activit\u00e9s hiver"}]},{"@type":"WebSite","@id":"https:\/\/www.talvenmaa.com\/#website","url":"https:\/\/www.talvenmaa.com\/","name":"Talvenmaa - Voyage en terre nordique","description":"S\u00e9jours multi-activit\u00e9s et exp\u00e9riences en Laponie","publisher":{"@id":"https:\/\/www.talvenmaa.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.talvenmaa.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.talvenmaa.com\/#organization","name":"Talvenmaa","url":"https:\/\/www.talvenmaa.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.talvenmaa.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.talvenmaa.com\/wp-content\/uploads\/2025\/07\/Rendu-final-01-1-scaled.jpg","contentUrl":"https:\/\/www.talvenmaa.com\/wp-content\/uploads\/2025\/07\/Rendu-final-01-1-scaled.jpg","width":2560,"height":2560,"caption":"Talvenmaa"},"image":{"@id":"https:\/\/www.talvenmaa.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/talvenmaa","https:\/\/www.instagram.com\/alex.axel.experience.nordique\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.talvenmaa.com\/en\/wp-json\/wp\/v2\/pages\/344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.talvenmaa.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.talvenmaa.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.talvenmaa.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.talvenmaa.com\/en\/wp-json\/wp\/v2\/comments?post=344"}],"version-history":[{"count":199,"href":"https:\/\/www.talvenmaa.com\/en\/wp-json\/wp\/v2\/pages\/344\/revisions"}],"predecessor-version":[{"id":2055,"href":"https:\/\/www.talvenmaa.com\/en\/wp-json\/wp\/v2\/pages\/344\/revisions\/2055"}],"up":[{"embeddable":true,"href":"https:\/\/www.talvenmaa.com\/en\/wp-json\/wp\/v2\/pages\/921"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.talvenmaa.com\/en\/wp-json\/wp\/v2\/media\/1579"}],"wp:attachment":[{"href":"https:\/\/www.talvenmaa.com\/en\/wp-json\/wp\/v2\/media?parent=344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}